{"id":123394,"date":"2024-11-28T11:31:01","date_gmt":"2024-11-28T11:31:01","guid":{"rendered":"https:\/\/cembogatell.com\/?page_id=123394"},"modified":"2024-12-24T11:43:14","modified_gmt":"2024-12-24T11:43:14","slug":"normativa-centro","status":"publish","type":"page","link":"https:\/\/cembogatell.com\/es\/normativa-centro\/","title":{"rendered":"Normativa del centro"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"123394\" class=\"elementor elementor-123394 elementor-123337\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad1f5c5 e-flex e-con-boxed e-con e-parent\" data-id=\"ad1f5c5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-379f436 elementor-widget elementor-widget-heading\" data-id=\"379f436\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Normativa del centro<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-706c8bd elementor-widget elementor-widget-heading\" data-id=\"706c8bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Instalaciones<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddbef13 elementor-widget elementor-widget-text-editor\" data-id=\"ddbef13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El\u00a0CEM\u00a0Bogatell\u00a0es una equipaci\u00f3n de titularidad municipal gestionado por CET10 centrado en la pr\u00e1ctica del f\u00fatbol sala.<br \/>Es un gran espacio dedicado al f\u00fatbol 7 y f\u00fatbol sala que est\u00e1 situado en la zona de la Vila Ol\u00edmpica y cuenta con unos 3.600 m\u00b2 de instalaci\u00f3n, con vestuarios, campo de f\u00fatbol y servicio de bar<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5fffe1 elementor-widget elementor-widget-heading\" data-id=\"a5fffe1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1.1 Espacios deportivos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88344fe elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"88344fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 campo de f\u00fatbol 7, dividido en tres campos de f\u00fatbol sala con c\u00e9sped de \u00faltima generaci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4de0df elementor-widget elementor-widget-heading\" data-id=\"d4de0df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">1.2 Procedimiento de entrada y salida<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6ecef5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f6ecef5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tienen acceso a las instalaciones del Centro Deportivo Municipal Bogatell:<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Sus abonados\/as.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Las personas que participan en alguna actividad organizada.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Las personas que hacen un uso puntual pagando la entrada.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Grupos que realizan una actividad organizada.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) P\u00fablico asistente a competiciones.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">El acceso y la salida de los usuarios\/as del centro es lo situado \u00fanicamente en la entrada principal, todo el mundo tiene que acceder por esta zona debidamente delimitada.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-691d11c elementor-widget elementor-widget-heading\" data-id=\"691d11c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Reglamento<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61b55a4 elementor-widget elementor-widget-text-editor\" data-id=\"61b55a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El Centre Esportiu Municipal&nbsp;Bogatell&nbsp;dispone de un reglamento de uso y de un r\u00e9gimen disciplinario que es de aplicaci\u00f3n a todos los usuarios\/aries del centro deportivo, y a los colectivos externos usuarios\/as del centro, as\u00ed como a todas las personas que acceden en el centro de forma espor\u00e1dica. La interpretaci\u00f3n y aplicaci\u00f3n o modificaci\u00f3n de este reglamento es facultad del \u00f3rgano competente del seguimiento del centro. El uso indebido de las instalaciones y de incumplimiento del reglamento pueden ser motivo de expulsi\u00f3n temporal o definitiva. La expulsi\u00f3n definitiva lo tiene que decidir el \u00f3rgano competente del seguimiento del centro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de2b1ba elementor-widget elementor-widget-heading\" data-id=\"de2b1ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">2.1 Procesos administrativos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f80a788 elementor-widget elementor-widget-heading\" data-id=\"f80a788\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Alquileres:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40e14ec elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"40e14ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Se tiene que abonar el importe correspondiente en el espacio reservado antes de entrar a pista. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Solo se puede hacer uso del espacio reservado. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) El alquiler de pista permite el acceso y utilizaci\u00f3n de los vestuarios.\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89c9526 elementor-widget elementor-widget-heading\" data-id=\"89c9526\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Escuela de Futbol Sala Poblenou<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cec96fa elementor-widget elementor-widget-heading\" data-id=\"cec96fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">A. Pago de cuotas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f240f35 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f240f35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) La reserva de plaza se formalizar\u00e1 de manera en l\u00ednea v\u00eda MatchPoint y el proceso se completar\u00e1 a las oficinas del Centro Deportivo Municipal y\/o a trav\u00e9s de la web del centro.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Los recibos se cobrar\u00e1n en los primeros 10 d\u00edas de cada mes mediante recibo bancario (domiciliaci\u00f3n).<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Las cuotas de la escuela se revisar\u00e1n una vez en el a\u00f1o.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f03a7d9 elementor-widget elementor-widget-heading\" data-id=\"f03a7d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">B. Cobro de cuotas impagadas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef4ee3 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1ef4ee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) El no abono de los recibos domiciliados antes de finalizar el curso, ocasionar\u00e1 la imposibilidad de reservar plaza de cara en el curso siguiente. Para volver a recuperarla hay que pagar los importes pendientes y los gastos de devoluci\u00f3n correspondientes.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) El gestor tiene la potestad de poner un recargo (m\u00e1ximo de un 5%). \u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c3297c elementor-widget elementor-widget-heading\" data-id=\"0c3297c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">C. Modificaci\u00f3n y bajas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4e797a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c4e797a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Las notificaciones de baja y las modificaciones de los datos bancarios hay que presentarlas antes del d\u00eda 20 del mes anterior. No se har\u00e1 ninguna devoluci\u00f3n si la baja se comunica con posterioridad. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) La notificaci\u00f3n habr\u00e1 que hacerla personalmente o por correo electr\u00f3nico, de tal manera que la petici\u00f3n quede grabada con la firma del solicitante, a quien se enviar\u00e1 una confirmaci\u00f3n de la baja. No se aceptar\u00e1 ninguna de estas gestiones por v\u00eda telef\u00f3nica.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7fc4e7 elementor-widget elementor-widget-heading\" data-id=\"f7fc4e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D. Otros<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a565c5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1a565c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) En caso de p\u00e9rdida de la llave de los vestuarios o del candado de las taquillas, hay que abonar el importe a la recepci\u00f3n del centro.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Sugerencias y quejas: los usuarios\/as disponen de un impreso para hacer llegar las sugerencias y las quejas que crean oportunas a la direcci\u00f3n del centro entreg\u00e1ndolo a la persona responsable del servicio de recepci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7112b1 elementor-widget elementor-widget-heading\" data-id=\"a7112b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. Normas generales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7598f61 elementor-widget elementor-widget-heading\" data-id=\"7598f61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.1 Definici\u00f3n de usuario\/a<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-472ffd2 elementor-widget elementor-widget-text-editor\" data-id=\"472ffd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Se entiende por usuario\/a cualquier persona f\u00edsica o jur\u00eddica que haga uso de la instalaci\u00f3n deportiva, en cualquier modalidad o disciplina, sea de manera puntual o prolongada y bajo cualquiera de las modalidades de uso. Tambi\u00e9n estar\u00e1n obligadas al cumplimiento de esta normativa aquellas personas que permanezcan para participar o presenciar un evento que tenga lugar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fc18b1 elementor-widget elementor-widget-heading\" data-id=\"7fc18b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Usuarios\/as puntuales o temporales<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4306a1c elementor-widget elementor-widget-text-editor\" data-id=\"4306a1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para adquirir esta condici\u00f3n, \u00fanicamente tiene que abonar el precio de la entrada o del abono previsto, y facilitar el nombre y el documento oficial que lo acredite.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c191d5f elementor-widget elementor-widget-heading\" data-id=\"c191d5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Usuarios\/as de cursos y\/o actividades<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8e1bcd elementor-widget elementor-widget-text-editor\" data-id=\"e8e1bcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Para adquirir la condici\u00f3n de persona inscrita en un curso o actividad, habr\u00e1 que hacer la solicitud correspondiente y la persona ser\u00e1 admitida en funci\u00f3n de las plazas previstas y por orden de inscripci\u00f3n. Cuando esta no pueda ser atendida por falta de disponibilidad de plazas, se integrar\u00e1 en una lista de espera por orden de presentaci\u00f3n, a efecto de acceder al curso o a la actividad en el momento que se produzca una vacante o ampliaci\u00f3n de plazas, si eso es posible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de3949e elementor-widget elementor-widget-heading\" data-id=\"de3949e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Clubs, entidades y asociaciones deportivas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-441ba2e elementor-widget elementor-widget-text-editor\" data-id=\"441ba2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Son aquellas entidades jur\u00eddicas que figuran legalmente inscritas en el Registro de Entidades Deportivas de la Generalitat y\/o en el Registro de Entidades del Ayuntamiento de Barcelona.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba93a84 elementor-widget elementor-widget-heading\" data-id=\"ba93a84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Centros docentes<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35e3f19 elementor-widget elementor-widget-text-editor\" data-id=\"35e3f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centros educativos de primaria y secundaria as\u00ed como escuelas especiales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f66072f elementor-widget elementor-widget-heading\" data-id=\"f66072f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Otros<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d719622 elementor-widget elementor-widget-text-editor\" data-id=\"d719622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Asociaciones culturales y\/o sociales la finalidad b\u00e1sica de las cuales no sea la pr\u00e1ctica f\u00edsico-deportiva ni el fomento de la actividad f\u00edsica\/el deporte, pero que lleven a cabo actividades f\u00edsico-deportivas para sus asociados y asociadas, as\u00ed como los grupos informales de usuarios\/as que lo soliciten. El r\u00e9gimen de autorizaci\u00f3n del uso de las instalaciones ser\u00e1 el previsto para los usuarios\/as individuales, la entidad gestora podr\u00e1 pedir la relaci\u00f3n de las personas que har\u00e1n uso como integrantes de este grupo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-701254a elementor-widget elementor-widget-heading\" data-id=\"701254a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.2 Derechos de los usuarios\/as<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e2d3f5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0e2d3f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Acceder a la instalaci\u00f3n y realizar las actividades f\u00edsico-deportivas en el horario establecido y para la finalidad para la cual acredite estar autorizado.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Realizar las actividades f\u00edsico-deportivas para las cuales tengan autorizaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Utilizar los servicios de acceso general de las instalaciones deportivas. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Formular reclamaciones, quejas y sugerencias en relaci\u00f3n con el servicio, siguiendo el procedimiento que haya establecido y recibir respuesta de las quejas o reclamaciones en el plazo de 15 d\u00edas h\u00e1biles a contar desde la fecha de su presentaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) Solicitar informaci\u00f3n sobre el funcionamiento la gesti\u00f3n de las instalaciones, as\u00ed como sobre programas y actividades deportivas.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) Ejercer los derechos de acceso, de rectificaci\u00f3n y de cancelaci\u00f3n, de acuerdo con el que determina la Ley Org\u00e1nica 15\/1999, de 13 de diciembre, de Protecci\u00f3n de Datos de Car\u00e1cter Personal. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">g) Conocer las caracter\u00edsticas de las instalaciones. Con cuyo objeto, CEM Bogatell mantendr\u00e1 actualizados los canales propios de informaci\u00f3n relativa a sus caracter\u00edsticas principales. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">h) Disponer de un reglamento de uso de consulta al azulejo de informaci\u00f3n as\u00ed como en la p\u00e1gina web del centro.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-326c869 elementor-widget elementor-widget-heading\" data-id=\"326c869\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.3 Obligaciones de los usuarios\/as de cumplimiento general<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68e086a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"68e086a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Hacer un buen uso de las instalaciones deportivas, respetarlas y cuidarlas, as\u00ed como el mobiliario y cualquier otro elemento que haya instalado. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Mostrar al personal al servicio de las instalaciones la autorizaci\u00f3n para usarlas, en el momento de acceder y en cualquier momento en que la pidan. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Aportar los datos necesarios para adquirir la condici\u00f3n de persona usuaria de las instalaciones o la condici\u00f3n de persona inscrita en un curso o actividad. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Colaborar en el mantenimiento de la limpieza de la instalaci\u00f3n y, con cuyo objeto, hacer uso de las papeleras y de los recipientes higi\u00e9nicos disponibles. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) Respetar el horario de funcionamiento del centro. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) Seguir las indicaciones e instrucciones que haga el personal de servicio. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">g) Es aconsejable comunicar al personal que presta servicio las alteraciones de funcionamiento, los desperfectos o las deficiencias en el funcionamiento de la instalaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">h) Tratar con respeto el resto de usuarios y de usuarias y el personal que trabaja. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">i) Respetar y tener cura del mobiliario, el material deportivo, los jardines y el arbolado. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">j) Abonar puntualmente las tasas y\/o precios p\u00fablicos establecidos para cada servicio o espacio deportivo y para cada modalidad de uso determinada. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">k) Efectuar la pr\u00e1ctica deportiva con el material y la vestimenta adecuada para cada tipo de instalaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">l) Abandonar la instalaci\u00f3n cuando hayan sido advertidos\/as del incumplimiento de la normativa y se nieguen a rectificar su conducta. A tal efecto, el personal de la instalaci\u00f3n tiene la capacidad de expulsar cualquier persona o entidad que no cumpla la normativa vigente, general o espec\u00edfica, que figura recogida como no permitida o como obligatoria para cada espacio, de acuerdo con la presente normativa de uso y con el resto de normativa legal que sea de aplicaci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">m) No est\u00e1 por permitido grabar im\u00e1genes ni sonidos a la instalaci\u00f3n por partes de los usuarios\/as. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">n) No est\u00e1 permitido fumar en ning\u00fan espacio de la instalaci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">o) No est\u00e1 permitido comer a la instalaci\u00f3n (fuera de la zona de bar). <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a26d15f elementor-widget elementor-widget-heading\" data-id=\"a26d15f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.4 De cumplimiento espec\u00edfico para usuarios\/as que pertenezcan a un colectivo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb1800e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bb1800e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Designar, ante CEM Bogatell y por escrito, la persona que representa la entidad a los efectos de elaborar el plan de usos de cada temporada o periodo.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Subscribir y mantener la vigencia de las p\u00f3lizas de seguro de responsabilidad civil que cubran las actividades que se tienen que realizar y las personas participantes, tan practicantes como p\u00fablico asistente, si se tercia. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Comunicar, con la urgencia necesaria, cualquier incidencia derivada de las actividades que se produzca durante su permanencia en la instalaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Utilizar la instalaci\u00f3n para la finalidad determinada en el acuerdo de utilizaci\u00f3n y seg\u00fan el calendario previsto en el plan de usos. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) Respetar el n\u00famero de usuarios\/aries de acuerdo con la comunicaci\u00f3n efectuada en el momento de la autorizaci\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) Solicitar autorizaci\u00f3n expresa de CEM Bogatell para modificar las condiciones de uso de los dos apartados anteriores. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">g) Adoptar las medidas necesarias por no interferir en los horarios y en las actividades del resto de usuarios y de usuarias de las instalaciones.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-249cb67 elementor-widget elementor-widget-heading\" data-id=\"249cb67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.5 Condiciones de acceso a las instalaciones deportivas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1d3625 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b1d3625\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Para acceder a la instalaci\u00f3n, el usuario\/a se tendr\u00e1 que identificar de la forma que se establezca, y utilizar adecuadamente los sistemas de control de acceso que existan en cada centro. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Los horarios de apertura y cierre de las instalaciones estar\u00e1n expuestos a la recepci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Los\/las usuarios\/as tendr\u00e1n que ajustarse en los d\u00edas y horas de apertura y cierre de las instalaciones y en los d\u00edas y periodos de cierre establecidos anualmente. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) En caso de llegar al aforo m\u00e1ximo, CEM Bogatell se reserva el derecho de cerrar el acceso a la instalaci\u00f3n, espacios o a las diferentes actividades. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) En las actividades de grupo que se vengan a hacer a las instalaciones, el responsable de las personas participantes mostrar\u00e1 a la persona encargada del control de acceso a la instalaci\u00f3n, su DNI o documento acreditativo, para poder acceder a los vestuarios y al resto de espacios deportivos. Para obtener las claves de los espacios que se tengan que utilizar, la persona responsable tendr\u00e1 que depositar un documento identificativo, que le ser\u00e1 devuelto una vez libradas las llaves en la salida.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07246d2 elementor-widget elementor-widget-heading\" data-id=\"07246d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">3.6 Otras condiciones de acceso<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6540b1a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6540b1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) El resto de personas que accedan a las instalaciones tendr\u00e1n que acreditar por los medios que se consideren suficientes su raz\u00f3n de entrada en los diferentes espacios. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Los usuarios y las usuarias no podr\u00e1n acceder a las instalaciones con veh\u00edculos, monopatines, patines, bicicletas o similares, ni con ning\u00fan enser o material que no est\u00e9 destinado a la pr\u00e1ctica deportiva para la cual est\u00e1n autorizados, salvo aquellas personas que lo necesiten por razones de movilidad reducida en atenci\u00f3n a su grado de discapacidad. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) No se permite la entrada de animales, salvo los perros lazarillo.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a935c79 elementor-widget elementor-widget-heading\" data-id=\"a935c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. Utilizaci\u00f3n general de espacios y de material deportivo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4920ef0 elementor-widget elementor-widget-heading\" data-id=\"4920ef0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.1 Uso de los espacios<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45bcb14 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"45bcb14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Tanto los usuarios y usuarias como las entidades ajenas al CEM Bogatell, tendr\u00e1n que respetar los horarios concedidos y no podr\u00e1n utilizarla fuera del tiempo autorizado. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) No se permite ocupar los espacios donde se est\u00e1n desarrollando actividades, o interferir. Tampoco se permite ocupar espacios libres sin autorizaci\u00f3n previa de los responsables de las instalaciones. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Se tiene que respetar la normativa espec\u00edfica en lo referente a cada espacio y el aforo m\u00e1ximo previsto para cada instalaci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b21b9f7 elementor-widget elementor-widget-heading\" data-id=\"b21b9f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.2 Uso del material deportivo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cc13ad elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9cc13ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Los usuarios\/as son responsables del material deportivo que utilizan, y lo tendr\u00e1n que devolver a su lugar una vez lo hayan usado. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Cada entidad deportiva es responsable del material deportivo que utilice. As\u00ed mismo, las entidades tendr\u00e1n que respetar la orden de los almacenes del material deportivo y tenerlo ordenado y guardado en el espacio asignado. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) El entrenador\/a o la persona responsable de cada entidad tendr\u00e1 que llevar el control del material utilizado para las actividades. Tambi\u00e9n se har\u00e1 responsable que, una vez finalizada la actividad, la instalaci\u00f3n, el material y los espacios deportivos empleados est\u00e9n en condiciones de volverse a utilizar. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Todo desperfecto ocasionado a la instalaci\u00f3n o al material a causa del mal uso ser\u00e1 responsabilidad de la persona que lo haya causado y, subsidiariamente, de la entidad a la cual pertenezca, si esta persona est\u00e1 en uso de la instalaci\u00f3n como integrante de un grupo. Los gastos de reparaci\u00f3n ir\u00e1n a cargo del declarado responsable.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f82a85a elementor-widget elementor-widget-heading\" data-id=\"f82a85a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.3 Pautas de comportamiento general<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93af89e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"93af89e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Las personas usuarias mantendr\u00e1n la limpieza y la orden de toda la instalaci\u00f3n, de la equipaci\u00f3n y del material deportivo, as\u00ed como un comportamiento respetuoso hacia el personal y el resto de gente que est\u00e9 presente. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Se tiene que velar porque se respeten al m\u00e1ximo todos los elementos de la instalaci\u00f3n y las normas espec\u00edficas de uso: hacer buen uso de las papeleras, dejar los vestuarios en buenas condiciones para las personas que vendr\u00e1n m\u00e1s tarde, etc. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Hay que respetar las normas y los consejos del personal de la instalaci\u00f3n deportiva. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) En general, no se permite realizar ninguna actuaci\u00f3n que altere el orden p\u00fablico o la convivencia normal y pac\u00edfica de las personas usuarias. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) Para la utilizaci\u00f3n del espacio deportivo, las usuarias y los usuarios\/aries tienen la obligaci\u00f3n de cambiarse los zapatos de la calle y usar calzado exclusivo y adecuado a la actividad deportiva, as\u00ed como de llevar ropa deportiva. No se podr\u00e1 hacer actividad f\u00edsica con ropa de calle.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) Es obligatorio utilizar siempre los vestuarios para cambiarse de ropa. No se permite de hacerlo en jefa otra dependencia de la instalaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">g) Se aconseja no llevar objetos de valor a la instalaci\u00f3n, puesto que la direcci\u00f3n no se responsabiliza de los objetos perdidos u olvidados.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d19924 elementor-widget elementor-widget-heading\" data-id=\"4d19924\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.4 Pautas de comportamiento saludables<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d0dd36 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6d0dd36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Es recomendable una revisi\u00f3n m\u00e9dica previa para el caso que se quiera iniciar una actividad deportiva. En todo caso, ser\u00e1 responsabilidad exclusiva de la persona usuaria cualquier tipo de incidente que por motivos de salud pueda sufrir, ya sea por desconocimiento de una posible enfermedad o por la realizaci\u00f3n de un sobreesfuerzo durante la pr\u00e1ctica deportiva. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) CEM Bogatell pone a disposici\u00f3n de las personas usuarias, durante todo el periodo de apertura de las instalaciones, se aconseja dirigirse al personal t\u00e9cnico que puede asesorarlas sobre la mejor manera de hacer actividad f\u00edsica. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Es recomendable hacer un calentamiento adecuado antes de empezar la actividad f\u00edsica y al acabarla, hacer ejercicios de estiramiento y de relajaci\u00f3n para volver a la calma, antes de ir a la ducha. En todo caso, ser\u00e1 responsabilidad exclusiva de la persona usuaria cualquier tipo de lesi\u00f3n provocada por una mala pr\u00e1ctica. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Durante las sesiones, es recomendable hidratarse bebiendo a menudo peque\u00f1as cantidades de agua. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) Es recomendable no comer desde dos horas antes de hacer ejercicio. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) En las sesiones dirigidas, hay que seguir los consejos del personal t\u00e9cnico y consultarle cualquier duda que se pueda tener.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3646cb6 elementor-widget elementor-widget-heading\" data-id=\"3646cb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.5. Objetos perdidos y disponibilidad de taquillas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ea5724 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4ea5724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) CEM Bogatell no se responsabiliza de los objetos depositados en las taquillas, igualmente tampoco se responsabiliza de los objetos perdidos u olvidados a las instalaciones. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Los objetos perdidos que se hayan podido recoger estar\u00e1n a disposici\u00f3n de las personas usuarias durante un mes. Transcurrido este plazo, el\/la responsable de la instalaci\u00f3n los destruir\u00e1 o dar\u00e1 a organizaciones no gubernamentales. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) No se recoger\u00e1n ni guardar\u00e1n jabones, cremas corporales, ni ropa interior.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-820d185 elementor-widget elementor-widget-heading\" data-id=\"820d185\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.6. Plafones informativos y web del CEM Bogatell<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41c19ce elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"41c19ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Los plafones informativos y el web son los espacios destinados a la difusi\u00f3n y a la comunicaci\u00f3n del funcionamiento del CEM Bogatell y de las actividades que se hacen. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Los responsables del CEM Bogatell gestionar\u00e1n el contenido del web y los diferentes plafones informativos y a tal efecto determinar\u00e1n los criterios de uso y la asignaci\u00f3n de estos, y podr\u00e1n hacer cualquier tipo de modificaci\u00f3n de acuerdo con las necesidades existentes. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) No se permite colocar ning\u00fan elemento de comunicaci\u00f3n, difusi\u00f3n, cartel ni publicidad fuera de los espacios adecuados y asignados en cada plaf\u00f3n sin la autorizaci\u00f3n de los responsables de los centros o de CEM Bogatell.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e04b044 elementor-widget elementor-widget-heading\" data-id=\"e04b044\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">4.7. Protecci\u00f3n de la imagen propia<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c815acd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"c815acd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A efectos de la Ley Org\u00e1nica 10\/1995 de 23 de noviembre, de protecci\u00f3n civil del honor, de la intimidad y de la propia imagen, la grabaci\u00f3n de im\u00e1genes (fotograf\u00edas, pel\u00edculas...) de cualquier tipo, se tratar\u00e1n de la siguiente manera: <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) CEM Bogatell, para garantizar los intereses de los usuarios\/aries establece que no se podr\u00e1 realizar grabaci\u00f3n de im\u00e1genes ni de sonido, en los espacios deportivos y complementarios cercados al p\u00fablico, figura del espectador, como norma general. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) En el caso de los espacios deportivos abiertos del CEM Bogatell se fomentar\u00e1 el car\u00e1cter informativo de la norma y se exime de la responsabilidad existente entre usuarios\/as. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4941aec elementor-widget elementor-widget-heading\" data-id=\"4941aec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Normativa de espacios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-735e2be elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"735e2be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">La Direcci\u00f3n del centro garantizar\u00e1 a todos los usuarios\/as: <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">El correcto mantenimiento de los espacios as\u00ed como del material y aparatos deportivos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">El servicio de asesoramiento y seguimiento a los abonados\/as.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf22b0 elementor-widget elementor-widget-heading\" data-id=\"bbf22b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5.1. Campos de futbol<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bcb31b elementor-widget elementor-widget-heading\" data-id=\"8bcb31b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Alquiler de espacios<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0746f4b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0746f4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Es obligatorio:<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Hacer la reserva en el \u00c1rea de Cliente v\u00eda Matchpoint o presencialmente a la recepci\u00f3n del centro. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) El responsable del grupo se tiene que presentar al personal de Atenci\u00f3n al Usuario\/a.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Hacer el pago del alquiler. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Llevar el propio material deportivo o pedirlo a la recepci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) Utilizar ropa deportiva y calzado deportivo.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-941c088 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"941c088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>No se permite:<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Desplazar las porter\u00edas o manipular las cortinas sin la autorizaci\u00f3n del personal de la instalaci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86114b1 elementor-widget elementor-widget-heading\" data-id=\"86114b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5.2. Vestuarios<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd72f6b elementor-widget elementor-widget-heading\" data-id=\"dd72f6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Horario<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48057d8 elementor-widget elementor-widget-text-editor\" data-id=\"48057d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"flex-basis: var(--flex-basis); flex-grow: var(--flex-grow); flex-shrink: var(--flex-shrink); order: var(--order); align-self: var(--align-self); flex-direction: var(--flex-direction); flex-wrap: var(--flex-wrap); justify-content: var(--justify-content); align-items: var(--align-items); align-content: var(--align-content); gap: var(--gap); --swiper-theme-color: #000; --swiper-navigation-size: 44px; --swiper-pagination-bullet-size: 6px; --swiper-pagination-bullet-horizontal-gap: 6px; --widgets-spacing: 20px 20px; font-family: Roboto, sans-serif; font-weight: 400; max-width: 100%;\" data-id=\"e5f58b5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div style=\"margin-top: -5px; transition: background .3s,border .3s,border-radius .3s,box-shadow .3s,transform var(--e-transform-transition-duration,.4s); height: 26px;\"><p>De lunes a viernes de 10:00 a 24:00 h \/ s\u00e1bados, domingos y festivos de 9:00 a 21:00 h.<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f1a33bd elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f1a33bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">La Direcci\u00f3n del centro garantizar\u00e1 a todos los usuarios\/as:<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Servicio de limpieza y desinfecci\u00f3n diario.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Taquillas para depositar ropa y objetos personales.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chevron-circle-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Duchas, lavabos y vestuarios adaptados a personas con movilidad reducida.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1ff9d8 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b1ff9d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Es obligatorio: <\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Velar por su buen mantenimiento y dejarlos en buenas condiciones para los usuarios\/aries posteriores. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Ducharse en el tiempo estrictamente necesario y hacer un consumo responsable del agua. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Secarse en la zona de duchas, as\u00ed como para escurrir el ba\u00f1ador. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) No dejar envases, envoltorios, restos de jab\u00f3n o cualquier otro objeto en el suelo de las duchas. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) Dejar libre la taquilla al abandonar la instalaci\u00f3n. Cada noche se proceder\u00e1 a vaciarlas para limpiarlas. Los objetos que se encuentren se custodiar\u00e1n a la recepci\u00f3n del centro y los propietarios\/as dispondr\u00e1n de 15 d\u00edas para recogerlos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23252ec elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"23252ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>No se permite:<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) Comer ni fumar. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">g) Introducir objetos de vidrio o de cualquier otro material que pueda estallar o romper en pedazos peque\u00f1os. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">h) Pr\u00e1cticas que afecten la salubridad como depilarse, afeitarse, te\u00f1irse, hacerse la manicura o pedicura, etc. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">i) Lavar las zapatillas, ba\u00f1ador o cualquier tipo de ropa por motivos de higiene.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-facdf34 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"facdf34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b>Se recuerda:<\/b><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">j) Usar zapatillas. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">k) Una vez usada la taquilla, dejar la puerta cerrada a fin de evitar accidentes. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">l) CEM Bogatell no se hace responsable de los objetos depositados a los vestuarios y taquillas.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6be124c elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6be124c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c74807 elementor-widget elementor-widget-heading\" data-id=\"0c74807\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6. Incumplimiento de la normativa y sanciones <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9941bf elementor-widget elementor-widget-text-editor\" data-id=\"e9941bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>No ajustarse a las condiciones de uso que marca esta normativa constituye incumplimiento. Los incumplimientos se calificar\u00e1n en leves, graves y muy graves.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9efac9 elementor-widget elementor-widget-heading\" data-id=\"a9efac9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.1. Incumplimientos leves<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e8018d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2e8018d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) No ajustarse a las condiciones recogidas en la Normativa relativas al buen uso de las instalaciones, mobiliario, etc., cuando no comporten da\u00f1os a estos, que no representen maltrato, ni falten al respecto a las personas, ni suplantaci\u00f3n otras personas. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) No cumplir el plan de usos y\/o el horario de funcionamiento de las instalaciones. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) No seguir las instrucciones e indicaciones del personal de servicio en relaci\u00f3n con el uso correcto de las instalaciones y el funcionamiento de las actividades. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) No ajustarse a las condiciones establecidas como obligatorias en la normativa espec\u00edfica de uso de los diferentes espacios deportivos y elementos de las instalaciones. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) El resto de las condiciones de uso contenidas en la presente Normativa y que no est\u00e9n tipificadas como incumplimientos graves o muy graves. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) La reincidencia de tres faltas leves durante un a\u00f1o, comportar\u00e1 una falta grave. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faf600f elementor-widget elementor-widget-heading\" data-id=\"faf600f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.2. Incumplimientos graves<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4dc824 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f4dc824\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) No ajustarse a las condiciones recogidas en la Normativa relativas en los espacios deportivos, al buen uso de las instalaciones, mobiliario, etc., cuando comporten da\u00f1os a estos. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Comportamiento inc\u00edvico al resto de usuarios\/aries y\/o al personal que presta servicio a las instalaciones. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Negarse a abandonar la instalaci\u00f3n, cuando lo requiera el personal, por no haberse ajustado a la normativa y en caso de emergencia y\/o simulacro. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Utilizar la instalaci\u00f3n, de manera individual, para finalidades diferentes de aquellas para las cuales se ha concedido la autorizaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) No ajustarse en el plan de usos y\/o el horario de funcionamiento de las instalaciones cuando comporte afectaci\u00f3n al resto de usuarios\/aries o al servicio. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) Utilizar las instalaciones por parte de un colectivo con personas diferentes y\/o actividades diferentes de las que constan en la relaci\u00f3n que tienen los responsables del centro. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">g) Acceder a las instalaciones sin autorizaci\u00f3n o con la acreditaci\u00f3n de otra persona. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">h) No ajustarse a la normativa de acceso de menores de edad a las instalaciones. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">i) Los incumplimientos que causen da\u00f1os graves a las instalaciones, perjuicios graves a otros usuarios\/aries o perturben gravemente la marcha de los servicios y que no se encuentren calificadas de muy graves. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1100f63 elementor-widget elementor-widget-heading\" data-id=\"1100f63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.3. Incumplimientos muy graves<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83ff3ec elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"83ff3ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Proferir insultos, amenazas y\/o agresiones al resto de usuarios\/aries y\/o al personal que presta servicio en las instalaciones. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Utilizar la instalaci\u00f3n para actividades colectivas diferentes de aquellas para las cuales se ha concedido la autorizaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Utilizar las instalaciones deportivas para finalidades diferentes a las deportivas, sin la autorizaci\u00f3n correspondiente. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Llevar a cabo actividades prohibidas en esta Normativa cuando estas sean susceptibles de generar un rendimiento econ\u00f3mico.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) Los incumplimientos cuando causen da\u00f1os graves a las instalaciones, perjuicios graves a otros usuarios\/usuarias o perturben gravemente la marcha de los servicios. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) La reincidencia en incumplimientos graves se considerar\u00e1 incumplimiento muy grave.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7bd46c elementor-widget elementor-widget-heading\" data-id=\"f7bd46c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.4. Medidas a aplicar por incumplimiento de las condiciones de uso, competencia en la aplicaci\u00f3n y prescripci\u00f3n de las mismas<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb0e937 elementor-widget elementor-widget-text-editor\" data-id=\"cb0e937\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1 &#8211; No ajustarse a las condiciones de uso del CEM Bogatell por parte del usuario\/a comportar\u00e1 la adopci\u00f3n de las medidas siguientes:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0215b87 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0215b87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Incumplimientos leves: comunicaci\u00f3n por escrito, expulsi\u00f3n temporal de las instalaciones por un periodo de un d\u00eda en un mes. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Incumplimientos graves: comunicaci\u00f3n por escrito, suspensi\u00f3n del derecho a entrada a las instalaciones por un periodo de un mes hasta un a\u00f1o. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Incumplimientos muy graves: suspensi\u00f3n de la condici\u00f3n de usuario\/aria, por un periodo de un a\u00f1o hasta cinco a\u00f1os, as\u00ed como resarcir los da\u00f1os econ\u00f3micos que genere a la instalaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) Sanciones muy graves: no ingreso al resto de instalaciones deportivas de la ciudad.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3438b9f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3438b9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2 - La expulsi\u00f3n de las instalaciones, o cualquier otra medida encaminada a garantizar la seguridad y la orden en el Servicio, podr\u00e1 ser acordada por cualquier de los responsables de los centros o por cualquier trabajador de las instalaciones en caso de ausencia de estos, sin perjuicio de poder proponer al director del centro la adopci\u00f3n de las otras medidas previstas en este art\u00edculo. La expulsi\u00f3n de las instalaciones tendr\u00e1 car\u00e1cter inmediato y su duraci\u00f3n afectar\u00e1 al resto de la jornada en que se produzca el hecho que motiva la aplicaci\u00f3n de esta medida. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">3 - La suspensi\u00f3n del derecho en la entrada a las instalaciones podr\u00e1 ser acordada por el director\/a, en primera instancia, en caso de no ajustarse a las condiciones de uso previstas a los apartados b) y c) del art\u00edculo anterior, y posteriormente por el Consejo de Equipaci\u00f3n, en segunda instancia. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4 - El\/la director\/a del centro resolver\u00e1 imponer alguna de las medidas antes mencionadas, viste el informe previo de los trabajadores y coordinador\/a del \u00e1rea. La persona afectada tendr\u00e1 la posibilidad de alegar los argumentos que considere adecuados y de aportar elementos de prueba en su defensa en la audiencia previa que se le haga, sin perjuicio otras actuaciones y diligencias que crea oportunas. Contra la resoluci\u00f3n del director\/a del centro se podr\u00e1 interponer recurso ordinario.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">5 - La duraci\u00f3n de la medida aplicable se determinar\u00e1, de acuerdo con el principio de proporcionalidad, atendiendo la intencionalidad en la actuaci\u00f3n del interesado, la naturaleza de los perjuicios ocasionados, la reiteraci\u00f3n y la reincidencia.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">6 - El\/la director\/a del centro podr\u00e1 arbitrar las medidas cautelares necesarias para garantizar el cumplimiento de las condiciones de uso de la instalaci\u00f3n, sin perjuicio de la competencia de los coordinadores y, en todo caso, tendr\u00e1n que ser confirmadas por este\/a. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">7 - Las medidas que se prev\u00e9n en este art\u00edculo se aplicar\u00e1n sin perjuicio de las acciones disciplinarias, civiles o penales que correspondan seg\u00fan la legislaci\u00f3n vigente. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">8 - El Ayuntamiento de Barcelona y la junta de CET10 ser\u00e1 informada de las sanciones que se impongan a los posibles infractores de la normativa de utilizaci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9da36f5 elementor-widget elementor-widget-heading\" data-id=\"9da36f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.5. Responsabilidades<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5edebde elementor-widget elementor-widget-text-editor\" data-id=\"5edebde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ser\u00e1n responsables directos de las infracciones de esta Normativa:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb892af elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bb892af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) Las personas autoras materiales de las infracciones, sea por acci\u00f3n o por omisi\u00f3n, salvo los supuestos que sean menores de edad o que concurra en ellos alguna causa legal de inimputabilidad. En este caso, responder\u00e1n los padres, las madres, los tutores, las tutoras o aquellas personas que posean la custodia o guarda legal. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) Las entidades o las personas responsables del usuario\/a, cuando el infractor\/a realice la actividad formando parte de un colectivo, ser\u00e1n, tambi\u00e9n, responsables de las infracciones que aquella persona realice. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Las personas titulares de autorizaciones o licencias, cuando, con motivo del ejercicio de un derecho que se los ha concedido, cometan una de las infracciones especificadas en esta Normativa.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed3d401 elementor-widget elementor-widget-text-editor\" data-id=\"ed3d401\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La declaraci\u00f3n de responsabilidad por infracci\u00f3n y la aplicaci\u00f3n de la medida correspondiente no evitar\u00e1n, en ning\u00fan caso, la obligaci\u00f3n de indemnizar los da\u00f1os y perjuicios causados.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a83675f elementor-widget elementor-widget-heading\" data-id=\"a83675f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">6.6. Garant\u00edas y plazos<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0aeb989 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0aeb989\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">a) No podr\u00e1n imponerse sanciones sin la instrucci\u00f3n previa de un expediente. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">b) La Comisi\u00f3n T\u00e9cnica de Gesti\u00f3n de la equipaci\u00f3n es el \u00f3rgano competente para iniciar el expediente de oficio o a instancia de cualquier parte; a tal efecto escuchar\u00e1 y, redactar\u00e1 un informe en el cual se detallar\u00e1 el supuesto del hecho y la resoluci\u00f3n del expediente, en un plazo m\u00e1ximo de 10 d\u00edas. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">c) Excepcionalmente y cuando sean necesarias para garantizar el normal desarrollo de las actividades o en el supuesto que se puedan deducir perjuicios graves, como medida cautelar, al iniciarse un expediente sancionador o en cualquier momento de la instrucci\u00f3n, la Comisi\u00f3n T\u00e9cnica de Gesti\u00f3n puede acordar la suspensi\u00f3n de la asistencia los entrenamientos o partidos o el acceso a las instalaciones por un periodo no superior al de la resoluci\u00f3n del expediente. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">d) La Comisi\u00f3n T\u00e9cnica de Gesti\u00f3n iniciar\u00e1 las actuaciones que estime pertinentes para elaborar el pliego de cargos o bien la propuesta de sobreseimiento y, con la audiencia previa de los inculpados y en los casos de padres o representantes legales y de su entrenador siempre que estos sean menores de edad, los cuales podr\u00e1n presentar las alegaciones, justificaciones y pruebas que estimen pertinentes. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">e) La resoluci\u00f3n del expediente tendr\u00e1 que producirse en el plazo m\u00e1ximo de un mes desde la fecha de su inicio. A no ser que causas justificadas determinadas por la complejidad de la instrucci\u00f3n as\u00ed lo requieran. En posterioridad ser\u00e1 ratificado por la Comisi\u00f3n de Seguimiento\/Equipaci\u00f3n. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">f) La notificaci\u00f3n de las resoluciones a los interesantes se har\u00e1n por escrito en mano o mediante correo certificado o correo electr\u00f3nico. <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">g) Contra esta resoluci\u00f3n, se puede interponer recurso potestativo de reposici\u00f3n en el plazo de quince d\u00edas ante el mismo \u00f3rgano que lo ha dictado o, directamente, recurso de alzada, que agota la v\u00eda administrativa, ante la Concejal\u00eda competente. Con la advertencia que contra la resoluci\u00f3n de este \u00faltimo recurso solo resta presentar recurso contencioso-administrativo ante los Juzgados Contenciosos Administrativos en el plazo de dos meses, ambos a contar desde el d\u00eda siguiente a la recepci\u00f3n de su notificaci\u00f3n.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Normativa del centro 1. Instalaciones El\u00a0CEM\u00a0Bogatell\u00a0es una equipaci\u00f3n de titularidad municipal gestionado por CET10 centrado en la pr\u00e1ctica del f\u00fatbol sala.Es un gran espacio dedicado al f\u00fatbol 7 y f\u00fatbol sala que est\u00e1 situado en la zona de la Vila Ol\u00edmpica y cuenta con unos 3.600 m\u00b2 de instalaci\u00f3n, con vestuarios, campo de f\u00fatbol y&hellip;<\/p>\n","protected":false},"author":88,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-123394","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Normativa del centro<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Normativa del centro\" \/>\n<meta property=\"og:description\" content=\"Normativa del centro 1. Instalaciones El\u00a0CEM\u00a0Bogatell\u00a0es una equipaci\u00f3n de titularidad municipal gestionado por CET10 centrado en la pr\u00e1ctica del f\u00fatbol sala.Es un gran espacio dedicado al f\u00fatbol 7 y f\u00fatbol sala que est\u00e1 situado en la zona de la Vila Ol\u00edmpica y cuenta con unos 3.600 m\u00b2 de instalaci\u00f3n, con vestuarios, campo de f\u00fatbol y&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cembogatell.com\/es\/normativa-centro\/\" \/>\n<meta property=\"og:site_name\" content=\"CEM Bogatell\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-24T11:43:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cembogatell.com\/es\/normativa-centro\/\",\"url\":\"https:\/\/cembogatell.com\/es\/normativa-centro\/\",\"name\":\"Normativa del centro\",\"isPartOf\":{\"@id\":\"https:\/\/cembogatell.com\/es\/#website\"},\"datePublished\":\"2024-11-28T11:31:01+00:00\",\"dateModified\":\"2024-12-24T11:43:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cembogatell.com\/es\/normativa-centro\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cembogatell.com\/es\/normativa-centro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cembogatell.com\/es\/normativa-centro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/cembogatell.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Normativa del centro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cembogatell.com\/es\/#website\",\"url\":\"https:\/\/cembogatell.com\/es\/\",\"name\":\"CEM Bogatell\",\"description\":\"Futbol sala, camp i escola de futbol a Barcelona\",\"publisher\":{\"@id\":\"https:\/\/cembogatell.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cembogatell.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cembogatell.com\/es\/#organization\",\"name\":\"CDM Escuelas de San Ant\u00f3n\",\"url\":\"https:\/\/cembogatell.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/cembogatell.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cembogatell.com\/wp-content\/uploads\/sites\/35\/2022\/01\/logo-bogatell-horitzontal-online-web-desktop.png\",\"contentUrl\":\"https:\/\/cembogatell.com\/wp-content\/uploads\/sites\/35\/2022\/01\/logo-bogatell-horitzontal-online-web-desktop.png\",\"width\":234,\"height\":80,\"caption\":\"CDM Escuelas de San Ant\u00f3n\"},\"image\":{\"@id\":\"https:\/\/cembogatell.com\/es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Normativa del centro","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Normativa del centro","og_description":"Normativa del centro 1. Instalaciones El\u00a0CEM\u00a0Bogatell\u00a0es una equipaci\u00f3n de titularidad municipal gestionado por CET10 centrado en la pr\u00e1ctica del f\u00fatbol sala.Es un gran espacio dedicado al f\u00fatbol 7 y f\u00fatbol sala que est\u00e1 situado en la zona de la Vila Ol\u00edmpica y cuenta con unos 3.600 m\u00b2 de instalaci\u00f3n, con vestuarios, campo de f\u00fatbol y&hellip;","og_url":"https:\/\/cembogatell.com\/es\/normativa-centro\/","og_site_name":"CEM Bogatell","article_modified_time":"2024-12-24T11:43:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"22 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cembogatell.com\/es\/normativa-centro\/","url":"https:\/\/cembogatell.com\/es\/normativa-centro\/","name":"Normativa del centro","isPartOf":{"@id":"https:\/\/cembogatell.com\/es\/#website"},"datePublished":"2024-11-28T11:31:01+00:00","dateModified":"2024-12-24T11:43:14+00:00","breadcrumb":{"@id":"https:\/\/cembogatell.com\/es\/normativa-centro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cembogatell.com\/es\/normativa-centro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cembogatell.com\/es\/normativa-centro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cembogatell.com\/es\/"},{"@type":"ListItem","position":2,"name":"Normativa del centro"}]},{"@type":"WebSite","@id":"https:\/\/cembogatell.com\/es\/#website","url":"https:\/\/cembogatell.com\/es\/","name":"CEM Bogatell","description":"Futbol sala, camp i escola de futbol a Barcelona","publisher":{"@id":"https:\/\/cembogatell.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cembogatell.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cembogatell.com\/es\/#organization","name":"CDM Escuelas de San Ant\u00f3n","url":"https:\/\/cembogatell.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cembogatell.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/cembogatell.com\/wp-content\/uploads\/sites\/35\/2022\/01\/logo-bogatell-horitzontal-online-web-desktop.png","contentUrl":"https:\/\/cembogatell.com\/wp-content\/uploads\/sites\/35\/2022\/01\/logo-bogatell-horitzontal-online-web-desktop.png","width":234,"height":80,"caption":"CDM Escuelas de San Ant\u00f3n"},"image":{"@id":"https:\/\/cembogatell.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cembogatell.com\/es\/wp-json\/wp\/v2\/pages\/123394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cembogatell.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cembogatell.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cembogatell.com\/es\/wp-json\/wp\/v2\/users\/88"}],"replies":[{"embeddable":true,"href":"https:\/\/cembogatell.com\/es\/wp-json\/wp\/v2\/comments?post=123394"}],"version-history":[{"count":0,"href":"https:\/\/cembogatell.com\/es\/wp-json\/wp\/v2\/pages\/123394\/revisions"}],"wp:attachment":[{"href":"https:\/\/cembogatell.com\/es\/wp-json\/wp\/v2\/media?parent=123394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}